{"id":4160,"date":"2017-07-14T13:18:52","date_gmt":"2017-07-14T11:18:52","guid":{"rendered":"https:\/\/www.pitchskills.com\/analizamos-el-discurso-de-steve-job-sobre-el-iphone-estas-son-las-8-lecciones-de-pitch-que-hemos-aprendido\/"},"modified":"2023-08-10T16:54:00","modified_gmt":"2023-08-10T14:54:00","slug":"analizamos-el-discurso-de-steve-job-sobre-el-iphone-estas-son-las-8-lecciones-de-pitch-que-hemos-aprendido","status":"publish","type":"post","link":"https:\/\/www.pitchskills.com\/es\/analizamos-el-discurso-de-steve-job-sobre-el-iphone-estas-son-las-8-lecciones-de-pitch-que-hemos-aprendido\/","title":{"rendered":"Analizamos el discurso de Steve Job sobre el Iphone. Estas son las 8 lecciones de pitch que hemos aprendido"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221; _builder_version=&#8221;3.0.47&#8243;][et_pb_row admin_label=&#8221;fila&#8221; _builder_version=&#8221;3.0.47&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.0.51&#8243; parallax=&#8221;off&#8221; parallax_method=&#8221;on&#8221;][et_pb_text _builder_version=&#8221;3.0.51&#8243;]<\/p>\n<h2>Lecciones de Steve Jobs.<\/h2>\n<\/p>\n<p class=\"\">Todos conocemos a Steve Jobs por sus famosos lanzamientos &#8220;reveladores&#8221;. Steve Jobs present\u00f3 muchos productos con un discurso, como el ipod, el iphone y el ipad.<\/p>\n<p class=\"\">Cada vez que Steve Jobs presentaba un nuevo producto, el p\u00fablico abandonaba la sala entusiasmado.<\/p>\n<p class=\"\">Hay muchas lecciones de lanzamiento que puedes aprender de Steve Jobs.<\/p>\n<p class=\"\">Por supuesto, es bastante f\u00e1cil entusiasmar a la gente cuando tu empresa es capaz de crear dispositivos de alta tecnolog\u00eda que est\u00e1n muy por delante de su tiempo. Pero no era s\u00f3lo el producto.<\/p>\n<\/p>\n<p>[\/et_pb_text][et_pb_cta title=&#8221;\u00bfHa recibido ya su empresa una inversi\u00f3n?&#8221; button_url=&#8221;https:\/\/www.pitchskills.com\/get-the-ultimate-pitch-guide\/&#8221; button_text=&#8221;Conozca los secretos para conseguir inversi\u00f3n en una startup&#8221; background_color=&#8221;#ffffff&#8221; background_layout=&#8221;light&#8221; _builder_version=&#8221;3.0.89&#8243; header_font=&#8221;||||||||&#8221; custom_padding=&#8221;50px||50px|&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;20px&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;#7dc86d&#8221; button_border_width=&#8221;11px&#8221; button_border_color=&#8221;#7dc86d&#8221; button_border_radius=&#8221;6px&#8221; button_font=&#8221;||||||||&#8221; button_use_icon=&#8221;off&#8221; button_bg_color_hover=&#8221;#074900&#8243; button_border_color_hover=&#8221;#074900&#8243; box_shadow_style_button=&#8221;preset2&#8243;][\/et_pb_cta][et_pb_text _builder_version=&#8221;3.0.51&#8243;]<\/p>\n<h3>\u00bfNo quiere leerlo todo? Estas son las 8 lecciones.<\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;3.0.51&#8243;]<\/p>\n<p><a href=\"#een\">#1 Los primeros 30 segundos s\u00f3lo se centra en despertar tu curiosidad<\/a><\/p>\n<p><a href=\"#twee\">#2 Construye credibilidad refiri\u00e9ndose a \u00e9xitos anteriores<\/a><\/p>\n<p><a href=\"#drie\">#3 Crea buena voluntad haciendo re\u00edr al p\u00fablico<\/a><\/p>\n<p><a href=\"#vier\">#4 Se burla de la competencia con im\u00e1genes de apoyo<\/a><\/p>\n<p><a href=\"#vijf\">#5 Utiliza muchas palabras de poder como &#8216;m\u00e1gico&#8217; y &#8216;fenomenal<\/a><\/p>\n<p><a href=\"#zes\">#6 Siempre se centra en los beneficios, nunca en las caracter\u00edsticas<\/a><\/p>\n<p><a href=\"#zeven\">#7 Investiga a fondo con qui\u00e9n est\u00e1 hablando<\/a><\/p>\n<p><a href=\"#acht\">#8 Agradece al p\u00fablico con humildad<\/a><\/p>\n<\/p>\n<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;3.0.51&#8243;]<\/p>\n<h3><strong>\u00bfC\u00f3mo estructur\u00f3 Steve Jobs su discurso?<\/strong><\/h3>\n<p class=\"\">1. Apertura (00:00)<\/p>\n<p class=\"\">2. Presentaci\u00f3n del problema (3:30)<\/p>\n<p class=\"\">3. Presentaci\u00f3n de su soluci\u00f3n (6:30)<\/p>\n<p class=\"\">4. Mencionar todos los beneficios (7:30)<\/p>\n<p class=\"\">5. Fin (1:17:00)<\/p>\n<p class=\"\"><a style=\"font-size: 16px;\" href=\"https:\/\/www.pitchskills.com\/build-structured-pitch\/\">Aqu\u00ed puedes ver c\u00f3mo estructurar t\u00fa mismo una presentaci\u00f3n.<\/a><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;3.0.51&#8243;]<\/p>\n<p><span style=\"text-decoration: underline;\"><strong style=\"font-size: 16px;\">La inauguraci\u00f3n <\/strong><span style=\"font-size: 16px; text-decoration-line: underline;\">(00:00)<\/span><\/span><\/p>\n<h3><strong><a id=\"een\"><\/a>#1 Los primeros 30 segundos s\u00f3lo se centra en despertar tu curiosidad.  <\/strong><\/h3>\n<p class=\"\">Llevo dos a\u00f1os y medio esperando este d\u00eda&#8221;.<\/p>\n<p class=\"\">De vez en cuando aparece un producto revolucionario que lo cambia todo&#8221;.<\/p>\n<p class=\"\">Eres afortunado si puedes trabajar en uno de estos productos en tu vida. Apple ha tenido la suerte de introducir algunos de estos&#8217;<\/p>\n<p class=\"\">Como puede ver, Steve Jobs viene con tres declaraciones seguidas. Todos ellos crean la sensaci\u00f3n de que va a hablar de algo alucinante.<\/p>\n<p class=\"\">As\u00ed consigue que todo el mundo le preste toda su atenci\u00f3n.<\/p>\n<\/p>\n<h3><strong><a id=\"twee\"><\/a>#2 Construye credibilidad refiri\u00e9ndose a \u00e9xitos anteriores<\/strong><\/h3>\n<p class=\"\">Aunque probablemente todo el mundo est\u00e9 familiarizado con los exitosos productos que Apple ha presentado hasta ahora, Steve no tarda en referirse a ellos.<\/p>\n<p class=\"\">Al referirse a \u00e9xitos anteriores, crea credibilidad para el resto de su discurso.<\/p>\n<\/p>\n<h3><b><a id=\"drie\"><\/a>#3 Crea buena voluntad haciendo re\u00edr al p\u00fablico<\/b><\/h3>\n<p class=\"\">Aunque Steve sea conocido como un hombre de negocios dif\u00edcil y duro, sin duda sabe c\u00f3mo utilizar el humor.<\/p>\n<p class=\"\">A lo largo de su discurso, Steve no deja de hacer peque\u00f1as bromas. El mejor ejemplo de este discurso es cuando habla de c\u00f3mo Apple va a introducir tres productos: Un Ipod, un tel\u00e9fono y un nuevo navegador de Internet.<\/p>\n<p class=\"\">Tras hablar de estos productos durante 2 minutos, confiesa que en realidad son todos combinados. As\u00ed, en lugar de presentar tres productos separados, ahora se centra en un &#8220;superproducto&#8221;.<\/p>\n<p class=\"\">Otro ejemplo es cuando muestra la foto del &#8216;nuevo&#8217; iphone, que obiamente no es el iphone real.<\/p>\n<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/www.pitchskills.com\/wp-content\/uploads\/2017\/07\/FUN-IPHONE.png&#8221; align=&#8221;center&#8221; _builder_version=&#8221;3.0.51&#8243; max_width=&#8221;250px&#8221; max_width_last_edited=&#8221;off|desktop&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; animation_duration=&#8221;500ms&#8221; animation_intensity_slide=&#8221;10%&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;3.0.51&#8243;][et_pb_row custom_padding=&#8221;|||&#8221; custom_margin=&#8221;|||&#8221; background_color=&#8221;rgba(224,224,224,0.21)&#8221; _builder_version=&#8221;3.0.89&#8243; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;#074900&#8243; border_style_all=&#8221;dashed&#8221; saved_tabs=&#8221;all&#8221; global_module=&#8221;3516&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.0.89&#8243; parallax=&#8221;off&#8221; parallax_method=&#8221;on&#8221;][et_pb_text _builder_version=&#8221;3.0.89&#8243; custom_padding=&#8221;|||30px&#8221; custom_padding_last_edited=&#8221;on|desktop&#8221;]<\/p>\n<h3><strong>Reciba &#8217;30 errores de lanzamiento que nunca debe cometer&#8217;  <\/strong><\/h3>\n<p><strong><\/strong>Haga clic en el bot\u00f3n y obtenga acceso directo<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;#&#8221; button_text=&#8221;Acceso directo&#8221; module_class=&#8221;trigger_popup&#8221; _builder_version=&#8221;3.0.89&#8243; custom_margin=&#8221;|||30px&#8221; custom_padding=&#8221;|||&#8221; custom_padding_last_edited=&#8221;on|desktop&#8221; custom_button=&#8221;on&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;#074900&#8243; button_border_color=&#8221;#074900&#8243; button_font=&#8221;||||||||&#8221; button_use_icon=&#8221;off&#8221; button_bg_color_hover=&#8221;#7dc86d&#8221; button_border_color_hover=&#8221;#7dc86d&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;3.0.51&#8243;][et_pb_row _builder_version=&#8221;3.0.51&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.0.51&#8243; parallax=&#8221;off&#8221; parallax_method=&#8221;on&#8221;][et_pb_text _builder_version=&#8221;3.0.51&#8243;]<\/p>\n<p><span style=\"text-decoration: underline;\"><strong style=\"font-size: 16px;\">2. El problema <\/strong><span style=\"font-size: 16px; text-decoration-line: underline;\">(03:30)<\/span><\/span><\/p>\n<h3><strong><a id=\"vier\"><\/a>#4 Se burla de la competencia con im\u00e1genes de apoyo<\/strong><\/h3>\n<p>En primer lugar, Steve habla del conjunto actual de tel\u00e9fonos inteligentes y explica al p\u00fablico que sus capacidades son limitadas.<\/p>\n<p class=\"\">Justo despu\u00e9s de hablar de la oferta existente de smartphones, muestra una imagen que compara el Iphone con los dem\u00e1s.<\/p>\n<p><span style=\"font-size: 16px;\"> <\/span><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/www.pitchskills.com\/wp-content\/uploads\/2017\/07\/IPHONE-VS-COMPETITION.png&#8221; _builder_version=&#8221;3.0.51&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; animation_duration=&#8221;500ms&#8221; animation_intensity_slide=&#8221;10%&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;3.0.51&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.0.51&#8243; parallax=&#8221;off&#8221; parallax_method=&#8221;on&#8221;][et_pb_text _builder_version=&#8221;3.0.51&#8243;]<\/p>\n<p class=\"\">Ahora Steve ha explicado lo que piensa del Iphone frente a la competencia, y lo respalda con un ejemplo.<\/p>\n<p class=\"\">De nuevo, utiliza una imagen que muestra el conjunto actual de teclados.<\/p>\n<p class=\"\">&#8220;Es rid\u00edculo tener un conjunto de teclados fijos, cuando cada situaci\u00f3n requiere un teclado diferente&#8221;<\/p>\n<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/www.pitchskills.com\/wp-content\/uploads\/2017\/07\/KEYBOARD-VS-COMPETITION.png&#8221; _builder_version=&#8221;3.0.51&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; animation_duration=&#8221;500ms&#8221; animation_intensity_slide=&#8221;10%&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;3.0.51&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.0.51&#8243; parallax=&#8221;off&#8221; parallax_method=&#8221;on&#8221;][et_pb_text _builder_version=&#8221;3.0.51&#8243;]<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>3. La soluci\u00f3n <\/strong>(06:30)<\/span><\/p>\n<p class=\"\">Ahora que Steve ha explicado por qu\u00e9 los otros smartphones no funcionan bien, es hora de mostrar la soluci\u00f3n.<\/p>\n<h3><strong><a id=\"vijf\"><\/a>#5 Utiliza muchas palabras de poder como &#8216;m\u00e1gico&#8217; y &#8216;fenomenal<\/strong><\/h3>\n<p class=\"\">Cuando Steve presenta el Iphone, utiliza muchas palabras poderosas. Aqu\u00ed tienes una lista de las palabras que utiliz\u00f3 Steve:<\/p>\n<ul>\n<li>Magia<\/li>\n<li>Inventado<\/li>\n<li>Fenomenal<\/li>\n<li>Preciso<\/li>\n<li>S\u00faper inteligente<\/li>\n<\/ul>\n<p class=\"\"><a href=\"https:\/\/www.pitchskills.com\/13-power-words-you-should-use-in-your-investor-pitch\/\"><span style=\"text-decoration: underline;\">Puede obtener m\u00e1s informaci\u00f3n sobre las palabras poderosas aqu\u00ed.<\/span><\/a><\/p>\n<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/www.pitchskills.com\/wp-content\/uploads\/2017\/07\/SOLUTION-BENEFITS.png&#8221; _builder_version=&#8221;3.0.51&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; animation_duration=&#8221;500ms&#8221; animation_intensity_slide=&#8221;10%&#8221;][\/et_pb_image][et_pb_cta title=&#8221;\u00bfHa recibido ya su empresa una inversi\u00f3n?&#8221; button_url=&#8221;https:\/\/www.pitchskills.com\/get-the-ultimate-pitch-guide\/&#8221; button_text=&#8221;Conozca los secretos para conseguir inversi\u00f3n en una startup&#8221; background_color=&#8221;#ffffff&#8221; background_layout=&#8221;light&#8221; _builder_version=&#8221;3.0.89&#8243; header_font=&#8221;||||||||&#8221; custom_padding=&#8221;50px||50px|&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;20px&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;#7dc86d&#8221; button_border_width=&#8221;11px&#8221; button_border_color=&#8221;#7dc86d&#8221; button_border_radius=&#8221;6px&#8221; button_font=&#8221;||||||||&#8221; button_use_icon=&#8221;off&#8221; button_bg_color_hover=&#8221;#074900&#8243; button_border_color_hover=&#8221;#074900&#8243; box_shadow_style_button=&#8221;preset2&#8243;][\/et_pb_cta][et_pb_text _builder_version=&#8221;3.0.51&#8243;]<\/p>\n<p class=\"\"><span style=\"text-decoration: underline;\"><strong>4. Los beneficios<\/strong><strong> (07:30)<\/strong><\/span><\/p>\n<h3><strong><a id=\"zes\"><\/a>#6 Siempre se centra en los beneficios, nunca en las caracter\u00edsticas<\/strong><\/h3>\n<p class=\"\">Un error que cometen muchos lanzadores u oradores p\u00fablicos es que se centran demasiado en las caracter\u00edsticas de un producto.<\/p>\n<p class=\"\">La gente no quiere saber qu\u00e9 software le permite hacer llamadas telef\u00f3nicas. La gente quiere o\u00edr que puede llamar a sus amigos, al otro lado del mundo, con s\u00f3lo dos toques de dedo.<\/p>\n<p class=\"\"><span style=\"text-decoration: underline;\"><strong>5. Fin<\/strong> (1:17:00)<\/span><\/p>\n<p class=\"\">Tras presentar el Iphone y hablar de todas sus funcionalidades, llega el momento de que Steve termine el discurso.<\/p>\n<p class=\"\">El final de una campa\u00f1a suele consistir en una llamada a la acci\u00f3n. Si esto fuera un discurso dirigido \u00fanicamente a clientes potenciales, una buena llamada a la acci\u00f3n ser\u00eda:<\/p>\n<p class=\"\">Si quieres experimentar el smartphone del siglo XXI, hazte con un Iphone&#8221;.<\/p>\n<p class=\"\">Sin embargo, Steve no termin\u00f3 as\u00ed su discurso. Como sab\u00eda que no hablaba s\u00f3lo con clientes, lo termin\u00f3 de otra manera. Investigar a su p\u00fablico es la lecci\u00f3n n\u00famero 7.<\/p>\n<\/p>\n<h3><strong><a id=\"zeven\"><\/a>#7 Investiga a fondo con qui\u00e9n est\u00e1 hablando<\/strong><\/h3>\n<p class=\"\">Como Steve es consciente de la posible repercusi\u00f3n de su discurso, sabe que muchas personas ver\u00e1n este discurso. Por lo tanto, su grupo objetivo no s\u00f3lo est\u00e1 formado por clientes potenciales, sino tambi\u00e9n por posibles socios, inversores y otras partes interesadas.<\/p>\n<p class=\"\">Cuando se dirige a un solo grupo destinatario, es f\u00e1cil definir la llamada a la acci\u00f3n.<\/p>\n<p class=\"\">En este caso, Steve decidi\u00f3 terminar con una cita inspiradora. As\u00ed deja a todos con una sensaci\u00f3n positiva.<\/p>\n<p>&#8220;Hay una vieja cita de Wayne Gretzky que me encanta.  <em>Patino hacia donde va a estar el disco, no hacia donde ha estado.  <\/em>En Apple siempre lo hemos intentado. Y siempre lo haremos&#8221;.<\/p>\n<\/p>\n<h3><strong><a id=\"acht\"><\/a>#8 Agradece al p\u00fablico con humildad<\/strong><\/h3>\n<p class=\"\">Al final de su discurso, Steve concluye con estas sencillas palabras:<\/p>\n<p class=\"\"><em>Muchas gracias.<\/em><\/p>\n<p class=\"\">Simplemente dando las gracias a su p\u00fablico, consigue dos cosas:<\/p>\n<p class=\"\">1. Crea simpat\u00eda con su p\u00fablico<\/p>\n<p class=\"\">2. El p\u00fablico sabe que ha terminado y que es hora de aplaudir.<\/p>\n<h3><strong>Conclusi\u00f3n<\/strong><\/h3>\n<p class=\"\">Steve fue un maestro en la estructuraci\u00f3n y ejecuci\u00f3n de su discurso. Aunque es bastante f\u00e1cil cuando eres el Director General de una empresa impresionante, Steve hizo un gran trabajo captando la atenci\u00f3n desde el principio hasta el final.<\/p>\n<p class=\"\">Estas 8 lecciones del discurso de Steve tambi\u00e9n pueden servirte para tu propio discurso.<a href=\"https:\/\/www.youtube.com\/watch?v=9hUIxyE2Ns8\">  Si quieres ver el v\u00eddeo completo del discurso de Steve, haz clic aqu\u00ed.<\/a>  Cr\u00e9ditos a Applebub\/N2TechGeeks por subir este v\u00eddeo.<\/p>\n<\/p>\n<p>[\/et_pb_text][et_pb_video src=&#8221;https:\/\/www.youtube.com\/watch?v=9hUIxyE2Ns8&#8243; _builder_version=&#8221;3.0.51&#8243;][\/et_pb_video][et_pb_text _builder_version=&#8221;3.0.51&#8243; text_font_size=&#8221;22px&#8221; border_width_all=&#8221;0px&#8221; border_color_all=&#8221;#666666&#8243; border_style_all=&#8221;solid&#8221; use_border_color=&#8221;on&#8221; border_color=&#8221;#666666&#8243; border_width=&#8221;0px&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>Si te ha gustado este contenido, dale al bot\u00f3n de compartir. Significar\u00eda mucho para m\u00ed y ayuda a otros a ver el contenido tambi\u00e9n.<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_cta title=&#8221;\u00bfHa recibido ya su empresa una inversi\u00f3n?&#8221; button_url=&#8221;https:\/\/www.pitchskills.com\/get-the-ultimate-pitch-guide\/&#8221; button_text=&#8221;Conozca los secretos para conseguir inversi\u00f3n en una startup&#8221; background_color=&#8221;#ffffff&#8221; background_layout=&#8221;light&#8221; _builder_version=&#8221;3.0.89&#8243; header_font=&#8221;||||||||&#8221; custom_padding=&#8221;50px||50px|&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;20px&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;#7dc86d&#8221; button_border_width=&#8221;11px&#8221; button_border_color=&#8221;#7dc86d&#8221; button_border_radius=&#8221;6px&#8221; button_font=&#8221;||||||||&#8221; button_use_icon=&#8221;off&#8221; button_bg_color_hover=&#8221;#074900&#8243; button_border_color_hover=&#8221;#074900&#8243; box_shadow_style_button=&#8221;preset2&#8243;][\/et_pb_cta][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lecciones de Steve Jobs. Todos conocemos a Steve Jobs por sus famosos lanzamientos &#8220;reveladores&#8221;. Steve Jobs present\u00f3 muchos productos con un discurso, como el ipod, el iphone y el ipad. Cada vez que Steve Jobs presentaba un nuevo producto, el p\u00fablico abandonaba la sala entusiasmado. Hay muchas lecciones de lanzamiento que puedes aprender de Steve [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3932,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[138],"tags":[],"_links":{"self":[{"href":"https:\/\/www.pitchskills.com\/es\/wp-json\/wp\/v2\/posts\/4160"}],"collection":[{"href":"https:\/\/www.pitchskills.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pitchskills.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pitchskills.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pitchskills.com\/es\/wp-json\/wp\/v2\/comments?post=4160"}],"version-history":[{"count":5,"href":"https:\/\/www.pitchskills.com\/es\/wp-json\/wp\/v2\/posts\/4160\/revisions"}],"predecessor-version":[{"id":4165,"href":"https:\/\/www.pitchskills.com\/es\/wp-json\/wp\/v2\/posts\/4160\/revisions\/4165"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pitchskills.com\/es\/wp-json\/wp\/v2\/media\/3932"}],"wp:attachment":[{"href":"https:\/\/www.pitchskills.com\/es\/wp-json\/wp\/v2\/media?parent=4160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pitchskills.com\/es\/wp-json\/wp\/v2\/categories?post=4160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pitchskills.com\/es\/wp-json\/wp\/v2\/tags?post=4160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}